{"id":11000,"date":"2024-04-22T03:00:24","date_gmt":"2024-04-22T03:00:24","guid":{"rendered":"https:\/\/articles4revival.com\/?p=11000"},"modified":"2024-04-22T13:50:54","modified_gmt":"2024-04-22T13:50:54","slug":"preparation-a-devenir-un-dirigeant-lecole-du-service-z-t-fomum","status":"publish","type":"post","link":"https:\/\/articles4revival.com\/fr\/preparation-a-devenir-un-dirigeant-lecole-du-service-z-t-fomum\/","title":{"rendered":"Pr\u00e9paration \u00c0 Devenir Un Dirigeant &#8211;\u00a0 L\u2019\u00e9cole Du Service (Z.T. Fomum)"},"content":{"rendered":"<p style=\"text-align: justify;\">Qui veut \u00eatre un dirigeant spirituel un jour ? Beaucoup de gens veulent \u00eatre dirigeants mais ils ne r\u00e9alisent pas que c\u2019est le fruit du travail dur. Nous allons consid\u00e9rer la pr\u00e9paration de Josu\u00e9 \u00e0 devenir le prochain dirigeant.<\/p>\n<p style=\"text-align: justify;\">\u00ab Mo\u00efse monta avec Aaron, Nadab et Abihu, et soixante-dix anciens d\u2019Isra\u00ebl. Ils virent le Dieu d\u2019Isra\u00ebl; sous ses pieds, c\u2019\u00e9tait comme un ouvrage de saphir transparent, comme le ciel lui-m\u00eame dans sa puret\u00e9. Il n\u2019\u00e9tendit point sa main sur l\u2019\u00e9lite des enfants d\u2019Isra\u00ebl. Ils virent Dieu, et ils mang\u00e8rent et burent. <!--more-->L\u2019\u00c9ternel dit \u00e0 Mo\u00efse: Monte vers moi sur la montagne, et reste l\u00e0; je te donnerai des tables de pierre, la loi et les ordonnances que j\u2019ai \u00e9crites pour leur instruction. Mo\u00efse se leva, avec Josu\u00e9 qui le servait, et Mo\u00efse monta sur la montagne de Dieu. \u00bb (Exode 24 : 9-13)<\/p>\n<p style=\"text-align: justify;\">Qui fut invit\u00e9 ? Mo\u00efse, Aaron et ses fils et les soixante-dix anciens d\u2019Isra\u00ebl. Ils arriv\u00e8rent \u00e0 un niveau de la montagne et s\u2019arr\u00eat\u00e8rent. Dieu dit \u00e0 Mo\u00efse : \u00ab monte vers moi \u2026 \u00bb au-del\u00e0 du lieu o\u00f9 les autres s\u2019\u00e9taient arr\u00eat\u00e9s. Pour continuer, il fallait une nomination divine. Seul Mo\u00efse pouvait monter. Mo\u00efse fut appel\u00e9 \u00e0 monter. Josu\u00e9 ne fut pas appel\u00e9. Il ne monta que parce qu\u2019il \u00e9tait serviteur. Celui qu\u2019il servait fut appel\u00e9 \u00e0 monter. Josu\u00e9 monta, progressa au-del\u00e0 des autres parce qu\u2019il \u00e9tait un serviteur et non un dirigeant officiel. \u00ab Les dirigeants officiels s\u2019\u00e9taient arr\u00eat\u00e9s \u00e0 un certain niveau. Mo\u00efse devait continuer, et il avait besoin de quelqu\u2019un pour porter son sac, et son serviteur Josu\u00e9 monta avec lui. \u00ab Il dit aux anciens : Attendez-nous ici, jusqu\u2019\u00e0 ce que nous revenions aupr\u00e8s de vous. Voici, Aaron et Hur resteront avec vous ; si quelqu\u2019un a un diff\u00e9rend, c\u2019est \u00e0 eux qu\u2019il s\u2019adressera. Mo\u00efse monta sur la montagne, et la nu\u00e9e couvrit la montagne. La gloire de l\u2019\u00c9ternel reposa sur la montagne de Sina\u00ef, et la nu\u00e9e le couvrit pendant six jours. Le septi\u00e8me jour, l\u2019\u00c9ternel appela Mo\u00efse du milieu de la nu\u00e9e. \u00bb (Exode 24 : 14-16).<\/p>\n<p style=\"text-align: justify;\">Seul Josu\u00e9, en dehors de Mo\u00efse \u00e9tait permis d\u2019entrer dans la pr\u00e9sence de Dieu, et il vit le mod\u00e8le c\u00e9leste parce qu\u2019il \u00e9tait serviteur. Le souverain sacrificateur et les anciens ne virent point le mod\u00e8le c\u00e9leste. Josu\u00e9 n\u2019avait pas vu le mod\u00e8le c\u00e9leste en tant qu\u2019une personne nomm\u00e9e, mais en tant que serviteur. C\u2019\u00e9tait donc \u00e9vident que le choix du prochain dirigeant devrait \u00eatre quelqu\u2019un qui a vu le mod\u00e8le c\u00e9leste, et seul Josu\u00e9 l\u2019avait vu.<\/p>\n<p style=\"text-align: justify;\">Mo\u00efse \u00e9tait satisfait de garder Josu\u00e9 dans l\u2019ombre. La mani\u00e8re la plus facile de d\u00e9truire un jeune homme ayant du potentiel c\u2019est de l\u2019\u00e9lever avant qu\u2019il n\u2019ait \u00e9tabli une histoire avec Dieu. Il faut qu\u2019il soit dou\u00e9, talentueux et oint, mais l\u2019\u00e9lever avant qu\u2019il n\u2019ait eu du temps pour d\u00e9velopper des racines dans le caract\u00e8re c\u2019est le d\u00e9truire. Pour une utilit\u00e9 et un minist\u00e8re durable, le but de Dieu est que les dons soient plac\u00e9s sur une solide fondation de caract\u00e8re. Mais un homme peut avoir des dons spirituels sans caract\u00e8re, une fois \u00e9lev\u00e9 sur un pi\u00e9destal, il est renvers\u00e9 par le vent. Mais un homme de caract\u00e8re et sans dons est tout de m\u00eame un homme de cons\u00e9quence. Les dons sans caract\u00e8re apporteront la ruine. Samson avait des dons mais sans caract\u00e8re. La pire des choses est que L\u2019\u00c9glise puisse \u00e9lever des jeunes gens qui n\u2019ont pas \u00e9t\u00e9 \u00e9prouv\u00e9s, qui n\u2019ont pas \u00e9t\u00e9 test\u00e9s, mais sont promus au sommet. Ils seront enterr\u00e9s. Ceux-l\u00e0 qui forment les gens, une fois qu\u2019ils trouvent quelqu\u2019un de promettant, ils le cachent afin qu\u2019il puisse d\u00e9velopper des racines, de profondes racines. Les racines sont enterr\u00e9es, cach\u00e9es aux yeux de l\u2019homme. Elles parlent de l\u2019histoire d\u2019un homme avec Dieu, de son histoire secr\u00e8te avec Dieu. Leonard Ravenhill dit que 90 % des \u00e9tudiants dans les \u00e9coles bibliques aux Etats-Unis n\u2019ont aucune vie de d\u00e9votion personnelle avec Dieu. Ils sont en formation pour aller tuer les gens. \u00c0 d\u00e9faut de racines dans la pri\u00e8re, dans la m\u00e9ditation, dans ce qui se passe entre un homme et Dieu seul, ses rencontres avec Dieu, son histoire avec Dieu, l\u2019apparition de Dieu \u00e0 l\u2019homme, etc. un homme est un ministre de mort.<\/p>\n<p style=\"text-align: justify;\">Les Fondations Pour Un Minist\u00e8re Abondant Et Durable<\/p>\n<p style=\"text-align: justify;\">S\u2019il y a des racines, ensuite, le caract\u00e8re et les dons, il y aura un minist\u00e8re abondant et durable. Lorsque tu cueilles les fleurs d\u2019un arbre pour d\u00e9corer la maison, les fleurs fanent apr\u00e8s quelque temps. Les dons spirituels sont comme des fleurs sur un arbre de No\u00ebl. Si les fleurs sont sur un vrai arbre, c\u2019est bon.<\/p>\n<p style=\"text-align: justify;\">Josu\u00e9 \u00e9tait un serviteur, un \u00ab INCONNU \u00bb, le serviteur de Mo\u00efse. Il eut une rencontre avec Dieu et il \u00e9tait l\u00e0 pendant le je\u00fbne surnaturel dans la pr\u00e9sence de Dieu pendant 40 jours. Il vit le mod\u00e8le c\u00e9leste du tabernacle, il vit le mod\u00e8le c\u00e9leste. Il monta avec Mo\u00efse et redescendit avec Mo\u00efse. Ils furent dans la pr\u00e9sence imm\u00e9diate de Dieu.<\/p>\n<p style=\"text-align: justify;\">\u00ab Mo\u00efse retourna et descendit de la montagne, les deux tables du t\u00e9moignage dans sa main; les tables \u00e9taient \u00e9crites des deux cot\u00e9s, elles \u00e9taient \u00e9crites de l\u2019un et de l\u2019autre cot\u00e9. Les tables \u00e9taient l\u2019ouvrage de Dieu, et l\u2019\u00e9criture \u00e9tait l\u2019\u00e9criture de Dieu, grav\u00e9e sur les tables. Josu\u00e9 entendit la voix du peuple, qui poussait des cris, et il dit \u00e0 Mo\u00efse: Il y a un cri de guerre dans le camp. Mo\u00efse r\u00e9pondit: Ce n\u2019est ni un cri de vainqueurs, ni un cri de vaincus; ce que j\u2019entends, c\u2019est la voix de gens qui chantent. \u00bb (Exode 32 : 15-18)<\/p>\n<p style=\"text-align: justify;\">Josu\u00e9 avait entendu le bruit et essayait de le discerner. Il entendait comme un bruit de guerre ! Mo\u00efse le corrigea. Mo\u00efse lui permit de parler, il s\u2019exprima et fut corrig\u00e9. Il \u00e9tait en train d\u2019apprendre des le\u00e7ons intimes. Des le\u00e7ons qui plus tard seront d\u2019importance capitale. Il n\u2019attira aucune attention sur Lui-m\u00eame. Josu\u00e9 n\u2019avait jamais fait mention de sa pr\u00e9sence sur la montagne pendant 40 jours. Il voulait que seul Mo\u00efse soit mentionn\u00e9. Pour lui, seul Mo\u00efse devait \u00eatre vu et mentionn\u00e9. Il \u00e9tait un serviteur, il avait un c\u0153ur de serviteur. Josu\u00e9 pouvait \u00eatre ignor\u00e9 et il \u00e9tait tout \u00e0 fait \u00e0 l\u2019aise en cela. Il \u00e9tait en train d\u2019\u00eatre test\u00e9 pour voir s\u2019il pouvait \u00eatre un dirigeant. Le point o\u00f9 la plupart des gens sacrifient leur direction c\u2019est au niveau de la gloire. Il y a les trois choses :<\/p>\n<p style=\"text-align: justify;\">L\u2019or<\/p>\n<p style=\"text-align: justify;\">Les filles<\/p>\n<p style=\"text-align: justify;\">La gloire<\/p>\n<p style=\"text-align: justify;\">La plupart des gens ont enterr\u00e9 leurs carri\u00e8res spirituelles dans l\u2019une ou deux de ces choses. L\u2019argent a enterr\u00e9 plusieurs pr\u00e9dicateurs. La plupart des hommes qui tombent devant l\u2019argent tombent aussi devant les femmes. Quand un homme se prosterne devant l\u2019or, il se prosternera bient\u00f4t devant une femme. Les dirigeants d\u2019\u00e9glise sont-ils excommuni\u00e9s pour amour de l\u2019argent ? L\u2019amour de l\u2019argent dans le c\u0153ur fait plus de mal qu\u2019un homme qui tombe une fois dans l\u2019adult\u00e8re. Est-ce qu\u2019on excommunie les amoureux de la gloire ? La pire des choses que tu puisses faire \u00e0 un homme de Dieu c\u2019est de le louer. Tu deviens alors son ennemi. Pourquoi ? Quand tu donnes \u00e0 un homme la gloire maintenant, tu le prives de sa r\u00e9compense en ce jour. Pourquoi le priver de sa r\u00e9compense ? Dire \u00e0 un homme : \u00ab tu es un grand serviteur de Dieu ! \u00bb s\u2019il est un serviteur, alors il ne peut pas \u00eatre grand. Plus un homme sert, plus il se rabaisse. \u00c9lever les hommes, c\u2019est du monde. Revenons \u00e0 la Bible.<\/p>\n<p style=\"text-align: justify;\">Les vers rong\u00e8rent H\u00e9rode, mais les louanges des hommes le tu\u00e8rent. Ne deviens pas l\u2019ennemi de quelqu\u2019un en d\u00e9versant des louanges sur lui. Le titre le plus \u00e9lev\u00e9 que tu puisses donner \u00e0 un homme c\u2019est ce que Pierre a donn\u00e9 \u00e0 Paul \u201cNotre Fr\u00e8re Paul.\u201d Un certain homme se r\u00e9clamait \u00eatre Ap\u00f4tre, proph\u00e8te et \u00e9vang\u00e9liste.<\/p>\n<table>\n<tbody>\n<tr>\n<td><\/td>\n<td><\/td>\n<td><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p style=\"text-align: justify;\">Au lieu de lire la m\u00e9daille qu\u2019il portait sur lui comme il l\u2019aurait voulu (dans le sens vertical), quelqu\u2019un lu dans le sens horizontal les trois premi\u00e8res lettres : APE ! (ce qui signifie en anglais SINGE). Il faut un singe pour \u00eatre tout ceci.<\/p>\n<p style=\"text-align: justify;\">Josu\u00e9 \u00e9tait un serviteur et en tant que serviteur, il fut hiss\u00e9 \u00e0 de grandes hauteurs. \u00c0 cause d\u2019un bon c\u0153ur, il prit part aux choses qu\u2019il ne m\u00e9ritait pas et qu\u2019il n\u2019aurait jamais touch\u00e9es.<\/p>\n<p style=\"text-align: justify;\">\u00ab Mon serviteur Caleb\u2026 \u00bb (Nombres 14 :24)<\/p>\n<p style=\"text-align: justify;\">Dieu parle de \u00ab mon serviteur Caleb \u00bb et ne fait pas mention de Josu\u00e9. Dieu pr\u00e9sente cela comme si Caleb \u00e9tait parti seul. Josu\u00e9 fut mis en retrait par Dieu, tout aussi bien qu\u2019il fut mis en retrait par l\u2019homme. Mo\u00efse \u00e9tait le serviteur de Jethro pendant 40 ans avant de devenir le serviteur de Dieu, et Josu\u00e9 \u00e9tait le serviteur de Mo\u00efse pendant 40 ans avant de devenir le serviteur de Dieu. Ceux qui veulent commencer comme serviteurs de Dieu vont s\u2019\u00e9crouler tot ou tard. Les esclaves de l\u2019homme seront les premiers dans le royaume et les serviteurs de l\u2019homme seront les plus grands dans le royaume (Marc 11 : 42). Plusieurs ne veulent pas \u00eatre appel\u00e9s serviteur de l\u2019homme. Ils veulent \u00eatre appel\u00e9s serviteurs de Dieu. C\u2019est de l\u2019orgueil. Si nous voulons un rang \u00e9ternel, nous devons \u00eatre des serviteurs de l\u2019homme. Plusieurs veulent servir plusieurs personnes avant d\u2019avoir servi une personne. Pendant 40 ans, Josu\u00e9 \u00e9tait sous l\u2019ombre d\u2019un autre, bien qu\u2019il f\u00fbt un g\u00e9n\u00e9ral de guerre.<\/p>\n<p style=\"text-align: justify;\">\u00ab Et Josu\u00e9, fils de Nun, serviteur de Mo\u00efse depuis sa jeunesse, prit la parole et dit : Mo\u00efse, mon seigneur, emp\u00eache-les \u00bb (Nombres 11 :28)<\/p>\n<p style=\"text-align: justify;\">C\u2019\u00e9tait ici le g\u00e9n\u00e9ral de guerre d\u2019Isra\u00ebl appelant Mo\u00efse \u00ab mon seigneur \u00bb et \u00e9tant jaloux de sa direction. Les gens pr\u00e9f\u00e8rent avoir plusieurs proph\u00e8tes, et non un proph\u00e8te. Ils ne veulent \u00e9carter personne. Josu\u00e9 avait \u00e9t\u00e9 l\u2019aide de Mo\u00efse depuis sa jeunesse. C\u2019\u00e9tait un investissement \u00e0 vie. Il n\u2019\u00e9tait pas en train d\u2019attendre et de vouloir prendre la rel\u00e8ve. C\u2019\u00e9tait sa joie de servir Mo\u00efse. Il ne s\u2019attendait pas \u00e0 la chute de Mo\u00efse.<\/p>\n<p style=\"text-align: justify;\">\u00ab Mo\u00efse prit la tente et la dressa hors du camp, \u00e0 quelque distance; il l\u2019appela tente d\u2019assignation; et tous ceux qui consultaient l\u2019\u00c9ternel allaient vers la tente d\u2019assignation, qui \u00e9tait hors du camp. Lorsque Mo\u00efse se rendait \u00e0 la tente, tout le peuple se levait; chacun se tenait \u00e0 l\u2019entr\u00e9e de sa tente, et suivait des yeux Mo\u00efse, jusqu\u2019\u00e0 ce qu\u2019il f\u00fbt entr\u00e9 dans la tente. Et lorsque Mo\u00efse \u00e9tait entr\u00e9 dans la tente, la colonne de nu\u00e9e descendait et s\u2019arr\u00eatait \u00e0 l\u2019entr\u00e9e de la tente, et l\u2019\u00c9ternel parlait avec Mo\u00efse. Tout le peuple voyait la colonne de nu\u00e9e qui s\u2019arr\u00eatait \u00e0 l\u2019entr\u00e9e de la tente, tout le peuple se levait et se prosternait \u00e0 l\u2019entr\u00e9e de sa tente. L\u2019\u00c9ternel parlait avec Mo\u00efse face \u00e0 face, comme un homme parle \u00e0 son ami. Puis Mo\u00efse retournait au camp; mais son jeune serviteur, Josu\u00e9, fils de Nun, ne sortait pas du milieu de la tente.\u00bb (Exode 33 7-11)<\/p>\n<p style=\"text-align: justify;\">La tente \u00e9tait le lieu d\u2019assignation de l\u2019Eternel. Josu\u00e9 ne quittait pas la tente. Il \u00e9tait en train de se sp\u00e9cialiser dans la connaissance de Dieu. Il \u00e9tait en train de faire de Dieu sa sp\u00e9cialit\u00e9. Dieu \u00e9tait sa premi\u00e8re sp\u00e9cialit\u00e9. Mo\u00efse \u00e9tait sa deuxi\u00e8me sp\u00e9cialit\u00e9. Il se sp\u00e9cialisa dans la connaissance de Dieu et au service de Mo\u00efse, et quand ce fut le moment de d\u00e9signer un autre dirigeant, il connaissait Dieu et il avait servi Mo\u00efse. Mo\u00efse n\u2019avait pas demand\u00e9 le service de Josu\u00e9, Josu\u00e9 s\u2019\u00e9tait offert. La confusion observ\u00e9e apr\u00e8s la mort de Josu\u00e9 fut parce que personne ne s\u2019\u00e9tait offert pour servir Josu\u00e9. Le manteau pour le prochain dirigeant c\u2019est le manteau de la connaissance de Dieu et du service au dirigeant. Le manteau d\u2019\u00c9lie tomba sur son serviteur \u00c9lis\u00e9e. Que sais-tu au sujet de demeurer dans la pr\u00e9sence perp\u00e9tuelle de Dieu et au service d\u2019un autre ? Ton c\u0153ur est-il encore mall\u00e9able ? Vas-tu te sp\u00e9cialiser dans la connaissance de Dieu et dans le service d\u2019un serviteur de Dieu ?<\/p>\n<p style=\"text-align: justify;\"><a href=\"https:\/\/books2read.com\/Prayer-And-a-Walk-With-God\">Extrait du livre\u00a0: La Pri\u00e8re et La Marche Avec Dieu \u2013 Z.T. Fomum<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Qui veut \u00eatre un dirigeant spirituel un jour ? Beaucoup de gens veulent \u00eatre dirigeants mais ils ne r\u00e9alisent pas que c\u2019est le fruit du travail dur. Nous allons consid\u00e9rer la pr\u00e9paration de Josu\u00e9 \u00e0 devenir le prochain dirigeant. \u00ab Mo\u00efse monta avec Aaron, Nadab et Abihu, et soixante-dix anciens d\u2019Isra\u00ebl. Ils virent le Dieu [&hellip;]<\/p>\n","protected":false},"author":4645,"featured_media":10997,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"advanced_seo_description":"","jetpack_seo_html_title":"","jetpack_seo_noindex":false,"jetpack_seo_schema_type":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"jnews-multi-image_gallery":[],"jnews_single_post":[],"jnews_primary_category":[],"jnews_override_bookmark_settings":[],"jnews_review":[],"enable_review":"","type":"","name":"","summary":"","brand":"","sku":"","good":[],"bad":[],"score_override":"","override_value":"","rating":[],"price":[],"jnews_post_split":[],"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[94,125,129,128,130],"tags":[],"class_list":["post-11000","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-articles-edifiants","category-la-priere","category-le-discipulat","category-le-jeune","category-le-leadership"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/articles4revival.com\/wp-content\/uploads\/2024\/04\/BookBrushImage-2024-4-15-3-826.jpg?fit=1400%2C800&ssl=1","jetpack-related-posts":[],"jetpack_likes_enabled":true,"jetpack_sharing_enabled":true,"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/articles4revival.com\/fr\/wp-json\/wp\/v2\/posts\/11000","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/articles4revival.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/articles4revival.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/articles4revival.com\/fr\/wp-json\/wp\/v2\/users\/4645"}],"replies":[{"embeddable":true,"href":"https:\/\/articles4revival.com\/fr\/wp-json\/wp\/v2\/comments?post=11000"}],"version-history":[{"count":0,"href":"https:\/\/articles4revival.com\/fr\/wp-json\/wp\/v2\/posts\/11000\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/articles4revival.com\/fr\/wp-json\/wp\/v2\/media\/10997"}],"wp:attachment":[{"href":"https:\/\/articles4revival.com\/fr\/wp-json\/wp\/v2\/media?parent=11000"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/articles4revival.com\/fr\/wp-json\/wp\/v2\/categories?post=11000"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/articles4revival.com\/fr\/wp-json\/wp\/v2\/tags?post=11000"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}